{"id":16444,"date":"2024-03-16T10:33:27","date_gmt":"2024-03-16T10:33:27","guid":{"rendered":"https:\/\/america-latina.de\/?page_id=16444"},"modified":"2024-03-22T05:52:47","modified_gmt":"2024-03-22T05:52:47","slug":"datenschutzerklarung","status":"publish","type":"page","link":"http:\/\/america-latina.de\/pt\/datenschutzerklarung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"16444\" class=\"elementor elementor-16444\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-adedede elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"adedede\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa41c9f\" data-id=\"aa41c9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34ca531 color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"34ca531\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article id=\"post-1273\" class=\"post-1273 page type-page status-publish hentry\"><div class=\"entry-content\"><p>Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als \u201eDaten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, in mobilen Applikationen sowie innerhalb externer Onlinepr\u00e4senzen, wie z.B. unserer Social-Media-Profile (nachfolgend zusammenfassend bezeichnet als \u201eOnlineangebot\u201c).<\/p><p>Die verwendeten Begriffe sind nicht geschlechtsspezifisch.<br \/>Stand: 23. Dezember 2023<\/p><p>Inhalts\u00fcbersicht<\/p><p><strong>Einleitung<\/strong><\/p><p>Verantwortlicher \u00dcbersicht der Verarbeitungen<br \/>Ma\u00dfgebliche Rechtsgrundlagen<br \/>Sicherheitsma\u00dfnahmen<br \/>Einsatz von Cookies<br \/>Kommerzielle und gesch\u00e4ftliche Leistungen<br \/>Kontaktaufnahme<br \/>Kommunikation via Messenger<br \/>Bereitstellung des Onlineangebotes und Webhosting<br \/>Cloud-Dienste<br \/>Werbliche Kommunikation via E-Mail, Post, Fax oder Telefon<\/p><p><strong>Onlinemarketing<\/strong><\/p><p>Pr\u00e4senzen in sozialen Netzwerken<br \/>Plugins und eingebettete Funktionen sowie Inhalte<br \/>L\u00f6schung von Daten<br \/>\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<br \/>Rechte der betroffenen Personen<br \/>Begriffsdefinitionen<\/p><p><strong>Verantwortlicher<\/strong><\/p><p>Brazukas Brazilian Food<br \/>Herr Joao Batista Goncalves Da Silva<br \/>Michelfelder Weg 17 a<br \/>97318 Kitzingen<\/p><p>E-Mail-Adresse: info@brazukas.de<\/p><p><strong>\u00dcbersicht der Verarbeitungen<\/strong><\/p><p>Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer<\/p><p>Verarbeitung zusammen und verweist auf die betroffenen Personen.<\/p><p>Arten der verarbeiteten Daten<\/p><p>Bestandsdaten (z.B. Namen, Adressen).<br \/>Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos).<br \/>Kontaktdaten (z.B. E-Mail, Telefonnummern).<br \/>Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten).<\/p><p>Standortdaten (Daten, die den Standort des Endger\u00e4ts eines Endnutzers angeben).<\/p><p>Vertragsdaten (z.B. Vertragsgegenstand, Laufzeit, Kundenkategorie).<\/p><p>Zahlungsdaten (z.B. Bankverbindungen, Rechnungen, Zahlungshistorie).<\/p><p>Kategorien betroffener Personen<\/p><p>Besch\u00e4ftigte (z.B. Angestellte, Bewerber, ehemalige Mitarbeiter).<\/p><p>Gesch\u00e4fts- und Vertragspartner.<\/p><p>Interessenten.<\/p><p>Kommunikationspartner.<\/p><p>Kunden.<\/p><p>Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/p><p>Zwecke der Verarbeitung<\/p><p>Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/p><p>Besuchsaktionsauswertung.<\/p><p>B\u00fcro- und Organisationsverfahren.<\/p><p>Direktmarketing (z.B. per E-Mail oder postalisch).<\/p><p>Interessenbasiertes und verhaltensbezogenes Marketing.<\/p><p>Kontaktanfragen und Kommunikation.<\/p><p>Konversionsmessung (Messung der Effektivit\u00e4t von Marketingma\u00dfnahmen).<\/p><p>Profiling (Erstellen von Nutzerprofilen).<\/p><p>Remarketing.<\/p><p>Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher).<\/p><p>Sicherheitsma\u00dfnahmen.<\/p><p>Tracking (z.B. interessens-\/verhaltensbezogenes Profiling, Nutzung von Cookies).<\/p><p>Vertragliche Leistungen und Service.<\/p><p>Verwaltung und Beantwortung von Anfragen.<\/p><p>Ma\u00dfgebliche Rechtsgrundlagen<\/p><p>Im Folgenden teilen wir die Rechtsgrundlagen der Datenschutzgrundverordnung (DSGVO), auf deren<\/p><p>Basis wir die personenbezogenen Daten verarbeiten, mit. Bitte beachten Sie, dass zus\u00e4tzlich zu den<\/p><p>Regelungen der DSGVO die nationalen Datenschutzvorgaben in Ihrem bzw. unserem Wohn- und<\/p><p>Sitzland gelten k\u00f6nnen. Sollten ferner im Einzelfall speziellere Rechtsgrundlagen ma\u00dfgeblich sein,<\/p><p>teilen wir Ihnen diese in der Datenschutzerkl\u00e4rung mit.<\/p><p>Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO) \u2013 Die betroffene Person hat ihre Einwilligung in die<\/p><p>Verarbeitung der sie betreffenden personenbezogenen Daten f\u00fcr einen spezifischen Zweck oder<\/p><p>mehrere bestimmte Zwecke gegeben.<\/p><p>Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO) \u2013 Die Verarbeitung<\/p><p>ist f\u00fcr die Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder zur<\/p><p>Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, die auf Anfrage der betroffenen Person<\/p><p>erfolgen.<\/p><p>Rechtliche Verpflichtung (Art. 6 Abs. 1 S. 1 lit. c. DSGVO) \u2013 Die Verarbeitung ist zur Erf\u00fcllung einer<\/p><p>rechtlichen Verpflichtung erforderlich, der der Verantwortliche unterliegt.<\/p><p>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO) \u2013 Die Verarbeitung ist zur Wahrung der<\/p><p>berechtigten Interessen des Verantwortlichen oder eines Dritten erforderlich, sofern nicht die<\/p><p>Interessen oder Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz<\/p><p>personenbezogener Daten erfordern, \u00fcberwiegen.<\/p><p>Nationale Datenschutzregelungen in Deutschland: Zus\u00e4tzlich zu den Datenschutzregelungen der<\/p><p>Datenschutz-Grundverordnung gelten nationale Regelungen zum Datenschutz in Deutschland. Hierzu<\/p><p>geh\u00f6rt insbesondere das Gesetz zum Schutz vor Missbrauch personenbezogener Daten bei der<\/p><p>Datenverarbeitung (Bundesdatenschutzgesetz \u2013 BDSG). Das BDSG enth\u00e4lt insbesondere<\/p><p>Spezialregelungen zum Recht auf Auskunft, zum Recht auf L\u00f6schung, zum Widerspruchsrecht, zur<\/p><p>Verarbeitung besonderer Kategorien personenbezogener Daten, zur Verarbeitung f\u00fcr andere Zwecke<\/p><p>und zur \u00dcbermittlung sowie automatisierten Entscheidungsfindung im Einzelfall einschlie\u00dflich<\/p><p>Profiling. Des Weiteren regelt es die Datenverarbeitung f\u00fcr Zwecke des Besch\u00e4ftigungsverh\u00e4ltnisses<\/p><p>(\u00a7 26 BDSG), insbesondere im Hinblick auf die Begr\u00fcndung, Durchf\u00fchrung oder Beendigung von<\/p><p>Besch\u00e4ftigungsverh\u00e4ltnissen sowie die Einwilligung von Besch\u00e4ftigten. Ferner k\u00f6nnen<\/p><p>Landesdatenschutzgesetze der einzelnen Bundesl\u00e4nder zur Anwendung gelangen.<\/p><p>Sicherheitsma\u00dfnahmen<\/p><p>Wir treffen nach Ma\u00dfgabe der gesetzlichen Vorgaben unter Ber\u00fccksichtigung des Stands der Technik,<\/p><p>der Implementierungskosten und der Art, des Umfangs, der Umst\u00e4nde und der Zwecke der<\/p><p>Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\u00dfes der<\/p><p>Bedrohung der Rechte und Freiheiten nat\u00fcrlicher Personen geeignete technische und<\/p><p>organisatorische Ma\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\u00e4hrleisten.<\/p><p>Zu den Ma\u00dfnahmen geh\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\u00e4t und<\/p><p>Verf\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten<\/p><p>als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\u00fcgbarkeit<\/p><p>und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von<\/p><p>Betroffenenrechten, die L\u00f6schung von Daten und Reaktionen auf die Gef\u00e4hrdung der Daten<\/p><p>gew\u00e4hrleisten. Ferner ber\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der<\/p><p>Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des<\/p><p>Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.<\/p><p>SSL-Verschl\u00fcsselung (https): Um Ihre via unser Online-Angebot \u00fcbermittelten Daten zu sch\u00fctzen,<\/p><p>nutzen wir eine SSL-Verschl\u00fcsselung. Sie erkennen derart verschl\u00fcsselte Verbindungen an dem Pr\u00e4fix<\/p><p>https:\/\/ in der Adresszeile Ihres Browsers.<\/p><p>Einsatz von Cookies<\/p><p>Cookies sind Textdateien, die Daten von besuchten Websites oder Domains enthalten und von einem<\/p><p>Browser auf dem Computer des Benutzers gespeichert werden. Ein Cookie dient in erster Linie dazu,<\/p><p>die Informationen \u00fcber einen Benutzer w\u00e4hrend oder nach seinem Besuch innerhalb eines<\/p><p>Onlineangebotes zu speichern. Zu den gespeicherten Angaben k\u00f6nnen z.B. die Spracheinstellungen<\/p><p>auf einer Webseite, der Loginstatus, ein Warenkorb oder die Stelle, an der ein Video geschaut wurde,<\/p><p>geh\u00f6ren. Zu dem Begriff der Cookies z\u00e4hlen wir ferner andere Technologien, die die gleichen<\/p><p>Funktionen wie Cookies erf\u00fcllen (z.B., wenn Angaben der Nutzer anhand pseudonymer<\/p><p>Onlinekennzeichnungen gespeichert werden, auch als \u201eNutzer-IDs\u201c bezeichnet)<\/p><p>Die folgenden Cookie-Typen und Funktionen werden unterschieden<\/p><p>Tempor\u00e4re Cookies (auch: Session- oder Sitzungs-Cookies): Tempor\u00e4re Cookies werden sp\u00e4testens<\/p><p>gel\u00f6scht, nachdem ein Nutzer ein Online-Angebot verlassen und seinen Browser geschlossen hat.<\/p><p>Permanente Cookies: Permanente Cookies bleiben auch nach dem Schlie\u00dfen des Browsers<\/p><p>gespeichert. So kann beispielsweise der Login-Status gespeichert oder bevorzugte Inhalte direkt<\/p><p>angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\u00f6nnen die Interessen von<\/p><p>Nutzern, die zur Reichweitenmessung oder zu Marketingzwecken verwendet werden, in einem<\/p><p>solches Cookie gespeichert werden.<\/p><p>First-Party-Cookies: First-Party-Cookies werden von uns selbst gesetzt.<\/p><p>Third-Party-Cookies (auch: Drittanbieter-Cookies): Drittanbieter-Cookies werden haupts\u00e4chlich von<\/p><p>Werbetreibenden (sog. Dritten) verwendet, um Benutzerinformationen zu verarbeiten.<\/p><p>Notwendige (auch: essentielle oder unbedingt erforderliche) Cookies: Cookies k\u00f6nnen zum einen<\/p><p>f\u00fcr den Betrieb einer Webseite unbedingt erforderlich sein (z.B. um Logins oder andere<\/p><p>Nutzereingaben zu speichern oder aus Gr\u00fcnden der Sicherheit).<\/p><p>Statistik-, Marketing- und Personalisierungs-Cookies: Ferner werden Cookies im Regelfall auch im<\/p><p>Rahmen der Reichweitenmessung eingesetzt sowie dann, wenn die Interessen eines Nutzers oder<\/p><p>sein Verhalten (z.B. Betrachten bestimmter Inhalte, Nutzen von Funktionen etc.) auf einzelnen<\/p><p>Webseiten in einem Nutzerprofil gespeichert werden. Solche Profile dienen dazu, den Nutzern z.B.<\/p><p>Inhalte anzuzeigen, die ihren potentiellen Interessen entsprechen. Dieses Verfahren wird auch als<\/p><p>\u201eTracking\u201c, d.h., Nachverfolgung der potentiellen Interessen der Nutzer bezeichnet. . Soweit wir<\/p><p>Cookies oder \u201eTracking\u201c-Technologien einsetzen, informieren wir Sie gesondert in unserer<\/p><p>Datenschutzerkl\u00e4rung oder im Rahmen der Einholung einer Einwilligung.<\/p><p>Hinweise zu Rechtsgrundlagen: Auf welcher Rechtsgrundlage wir Ihre personenbezogenen Daten mit<\/p><p>Hilfe von Cookies verarbeiten, h\u00e4ngt davon ab, ob wir Sie um eine Einwilligung bitten. Falls dies<\/p><p>zutrifft und Sie in die Nutzung von Cookies einwilligen, ist die Rechtsgrundlage der Verarbeitung Ihrer<\/p><p>Daten die erkl\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verarbeiteten Daten auf<\/p><p>Grundlage unserer berechtigten Interessen (z.B. an einem betriebswirtschaftlichen Betrieb unseres<\/p><p>Onlineangebotes und dessen Verbesserung) verarbeitet oder, wenn der Einsatz von Cookies<\/p><p>erforderlich ist, um unsere vertraglichen Verpflichtungen zu erf\u00fcllen.<\/p><p>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-Out): Abh\u00e4ngig davon, ob die<\/p><p>Verarbeitung auf Grundlage einer Einwilligung oder gesetzlichen Erlaubnis erfolgt, haben Sie<\/p><p>jederzeit die M\u00f6glichkeit, eine erteilte Einwilligung zu widerrufen oder der Verarbeitung Ihrer Daten<\/p><p>durch Cookie-Technologien zu widersprechen (zusammenfassend als \u201eOpt-Out\u201c bezeichnet). Sie<\/p><p>k\u00f6nnen Ihren Widerspruch zun\u00e4chst mittels der Einstellungen Ihres Browsers erkl\u00e4ren, z.B., indem<\/p><p>Sie die Nutzung von Cookies deaktivieren (wobei hierdurch auch die Funktionsf\u00e4higkeit unseres<\/p><p>Onlineangebotes eingeschr\u00e4nkt werden kann). Ein Widerspruch gegen den Einsatz von Cookies zu<\/p><p>Zwecken des Onlinemarketings kann auch mittels einer Vielzahl von Diensten, vor allem im Fall des<\/p><p>Trackings, \u00fcber die Webseiten https:\/\/optout.aboutads.info und<\/p><p>https:\/\/www.youronlinechoices.com\/ erkl\u00e4rt werden. Daneben k\u00f6nnen Sie weitere<\/p><p>Widerspruchshinweise im Rahmen der Angaben zu den eingesetzten Dienstleistern und Cookies<\/p><p>erhalten.<\/p><p>Verarbeitete Datenarten: Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten,<\/p><p>Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Betroffene Personen: Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/p><p>Rechtsgrundlagen: Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs.<\/p><p>1 S. 1 lit. f. DSGVO).<\/p><p>Kommerzielle und gesch\u00e4ftliche Leistungen<\/p><p>Wir verarbeiten Daten unserer Vertrags- und Gesch\u00e4ftspartner, z.B. Kunden und Interessenten<\/p><p>(zusammenfassend bezeichnet als \u201eVertragspartner\u201c) im Rahmen von vertraglichen und<\/p><p>vergleichbaren Rechtsverh\u00e4ltnissen sowie damit verbundenen Ma\u00dfnahmen und im Rahmen der<\/p><p>Kommunikation mit den Vertragspartnern (oder vorvertraglich), z.B., um Anfragen zu beantworten.<\/p><p>Diese Daten verarbeiten wir zur Erf\u00fcllung unserer vertraglichen Pflichten, zur Sicherung unserer<\/p><p>Rechte und zu Zwecken der mit diesen Angaben einhergehenden Verwaltungsaufgaben sowie der<\/p><p>unternehmerischen Organisation. Die Daten der Vertragspartner geben wir im Rahmen des<\/p><p>geltenden Rechts nur insoweit an Dritte weiter, als dies zu den vorgenannten Zwecken oder zur<\/p><p>Erf\u00fcllung gesetzlicher Pflichten erforderlich ist oder mit Einwilligung der Vertragspartner erfolgt (z.B.<\/p><p>an beteiligte Telekommunikations-, Transport- und sonstige Hilfsdienste sowie Subunternehmer,<\/p><p>Banken, Steuer- und Rechtsberater, Zahlungsdienstleister oder Steuerbeh\u00f6rden). \u00dcber weitere<\/p><p>Verarbeitungsformen, z.B. zu Zwecken des Marketings, werden die Vertragspartner im Rahmen<\/p><p>dieser Datenschutzerkl\u00e4rung informiert.<\/p><p>Welche Daten f\u00fcr die vorgenannten Zwecke erforderlich sind, teilen wir den Vertragspartnern vor<\/p><p>oder im Rahmen der Datenerhebung, z.B. in Onlineformularen, durch besondere Kennzeichnung (z.B.<\/p><p>Farben) bzw. Symbole (z.B. Sternchen o.\u00e4.), oder pers\u00f6nlich mit.<\/p><p>Wir l\u00f6schen die Daten nach Ablauf gesetzlicher Gew\u00e4hrleistungs- und vergleichbarer Pflichten, d.h.,<\/p><p>grunds\u00e4tzlich nach Ablauf von 4 Jahren, es sei denn, dass die Daten in einem Kundenkonto<\/p><p>gespeichert werden, z.B., solange sie aus gesetzlichen Gr\u00fcnden der Archivierung aufbewahrt werden<\/p><p>m\u00fcssen (z.B. f\u00fcr Steuerzwecke im Regelfall 10 Jahre). Daten, die uns im Rahmen eines Auftrags durch<\/p><p>den Vertragspartner offengelegt wurden, l\u00f6schen wir entsprechend den Vorgaben des Auftrags,<\/p><p>grunds\u00e4tzlich nach Ende des Auftrags.<\/p><p>Soweit wir zur Erbringung unserer Leistungen Drittanbieter oder Plattformen einsetzen, gelten im<\/p><p>Verh\u00e4ltnis zwischen den Nutzern und den Anbietern die Gesch\u00e4ftsbedingungen und<\/p><p>Datenschutzhinweise der jeweiligen Drittanbieter oder Plattformen.<\/p><p>Agenturdienstleistungen: Wir verarbeiten die Daten unserer Kunden im Rahmen unserer<\/p><p>vertraglichen Leistungen, zu denen z.B. konzeptionelle und strategische Beratung,<\/p><p>Kampagnenplanung, Software- und Designentwicklung\/-beratung oder -pflege, Umsetzung von<\/p><p>Kampagnen und Prozessen, Handling, Serveradministration, Datenanalyse\/ Beratungsleistungen und<\/p><p>Schulungsleistungen geh\u00f6ren k\u00f6nnen.<\/p><p>Weitere Informationen zu kommerziellen Dienstleistungen: Wir verarbeiten die Daten unserer<\/p><p>Kunden sowie Auftraggeber (nachfolgend einheitlich als \u201eKunden\u201c bezeichnet), um ihnen die<\/p><p>Auswahl, den Erwerb bzw. die Beauftragung der gew\u00e4hlten Leistungen oder Werke sowie<\/p><p>verbundener T\u00e4tigkeiten als auch deren Bezahlung und Zustellung bzw. Ausf\u00fchrung oder Erbringung<\/p><p>zu erm\u00f6glichen.<\/p><p>Die erforderlichen Angaben sind als solche im Rahmen des Auftrags-, Bestell- bzw. vergleichbaren<\/p><p>Vertragsschlusses gekennzeichnet und umfassen die zur Leistungserbringung und Abrechnung<\/p><p>ben\u00f6tigten Angaben sowie Kontaktinformationen, um etwaige R\u00fccksprachen halten zu k\u00f6nnen.<\/p><p>Verarbeitete Datenarten: Bestandsdaten (z.B. Namen, Adressen), Zahlungsdaten (z.B.<\/p><p>Bankverbindungen, Rechnungen, Zahlungshistorie), Kontaktdaten (z.B. E-Mail, Telefonnummern),<\/p><p>Vertragsdaten (z.B. Vertragsgegenstand, Laufzeit, Kundenkategorie).<\/p><p>Betroffene Personen: Interessenten, Gesch\u00e4fts- und Vertragspartner.<\/p><p>Zwecke der Verarbeitung: Vertragliche Leistungen und Service, Kontaktanfragen und<\/p><p>Kommunikation, B\u00fcro- und Organisationsverfahren, Verwaltung und Beantwortung von Anfragen.<\/p><p>Rechtsgrundlagen: Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO),<\/p><p>Rechtliche Verpflichtung (Art. 6 Abs. 1 S. 1 lit. c. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit.<\/p><ol><li>DSGVO).<\/li><\/ol><p>Kontaktaufnahme<\/p><p>Bei der Kontaktaufnahme mit uns (z.B. per Kontaktformular, E-Mail, Telefon oder via soziale Medien)<\/p><p>werden die Angaben der anfragenden Personen verarbeitet, soweit dies zur Beantwortung der<\/p><p>Kontaktanfragen und etwaiger angefragter Ma\u00dfnahmen erforderlich ist.<\/p><p>Die Beantwortung der Kontaktanfragen im Rahmen von vertraglichen oder vorvertraglichen<\/p><p>Beziehungen erfolgt zur Erf\u00fcllung unserer vertraglichen Pflichten oder zur Beantwortung von<\/p><p>(vor)vertraglichen Anfragen und im \u00dcbrigen auf Grundlage der berechtigten Interessen an der<\/p><p>Beantwortung der Anfragen.<\/p><p>Verarbeitete Datenarten: Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail,<\/p><p>Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos).<\/p><p>Betroffene Personen: Kommunikationspartner.<\/p><p>Zwecke der Verarbeitung: Kontaktanfragen und Kommunikation.<\/p><p>Rechtsgrundlagen: Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO),<\/p><p>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/p><p>Kontaktaufnahme<\/p><p>Bei der Kontaktaufnahme mit uns (z.B. per Kontaktformular, E-Mail, Telefon oder via soziale Medien)<\/p><p>werden die Angaben der anfragenden Personen verarbeitet, soweit dies zur Beantwortung der<\/p><p>Kontaktanfragen und etwaiger angefragter Ma\u00dfnahmen erforderlich ist.<\/p><p>Die Beantwortung der Kontaktanfragen im Rahmen von vertraglichen oder vorvertraglichen<\/p><p>Beziehungen erfolgt zur Erf\u00fcllung unserer vertraglichen Pflichten oder zur Beantwortung von<\/p><p>(vor)vertraglichen Anfragen und im \u00dcbrigen auf Grundlage der berechtigten Interessen an der<\/p><p>Beantwortung der Anfragen.<\/p><p>Verarbeitete Datenarten: Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail,<\/p><p>Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos).<\/p><p>Betroffene Personen: Kommunikationspartner.<\/p><p>Zwecke der Verarbeitung: Kontaktanfragen und Kommunikation.<\/p><p>Rechtsgrundlagen: Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO),<\/p><p>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/p><p>Kommunikation via Messenger<\/p><p>Wir setzen zu Zwecken der Kommunikation Messenger ein und bitten daher darum, die<\/p><p>nachfolgenden Hinweise zur Funktionsf\u00e4higkeit der Messenger, zur Verschl\u00fcsselung, zur Nutzung der<\/p><p>Metadaten der Kommunikation und zu Ihren Widerspruchsm\u00f6glichkeiten zu beachten.<\/p><p>Sie k\u00f6nnen uns auch auf alternativen Wegen, z.B. via Telefon oder E-Mail, kontaktieren. Bitte nutzen<\/p><p>Sie die Ihnen mitgeteilten Kontaktm\u00f6glichkeiten oder die innerhalb unseres Onlineangebotes<\/p><p>angegebenen Kontaktm\u00f6glichkeiten.<\/p><p>Im Fall einer Ende-zu-Ende-Verschl\u00fcsselung von Inhalten (d.h., der Inhalt Ihrer Nachricht und<\/p><p>Anh\u00e4nge) weisen wir darauf hin, dass die Kommunikationsinhalte (d.h., der Inhalt der Nachricht und<\/p><p>angeh\u00e4ngte Bilder) von Ende zu Ende verschl\u00fcsselt werden. Das bedeutet, dass der Inhalt der<\/p><p>Nachrichten nicht einsehbar ist, nicht einmal durch die Messenger-Anbieter selbst. Sie sollten immer<\/p><p>eine aktuelle Version der Messenger mit aktivierter Verschl\u00fcsselung nutzen, damit die<\/p><p>Verschl\u00fcsselung der Nachrichteninhalte sichergestellt ist.<\/p><p>Wir weisen unsere Kommunikationspartner jedoch zus\u00e4tzlich darauf hin, dass die Anbieter der<\/p><p>Messenger zwar nicht den Inhalt einsehen, aber in Erfahrung bringen k\u00f6nnen, dass und wann<\/p><p>Kommunikationspartner mit uns kommunizieren sowie technische Informationen zum verwendeten<\/p><p>Ger\u00e4t der Kommunikationspartner und je nach Einstellungen ihres Ger\u00e4tes auch<\/p><p>Standortinformationen (sogenannte Metadaten) verarbeitet werden.<\/p><p>Hinweise zu Rechtsgrundlagen: Sofern wir Kommunikationspartner vor der Kommunikation mit ihnen<\/p><p>via Messenger um eine Erlaubnis bitten, ist die Rechtsgrundlage unserer Verarbeitung ihrer Daten<\/p><p>deren Einwilligung. Im \u00dcbrigen, falls wir nicht um eine Einwilligung bitten und sie z.B. von sich aus<\/p><p>Kontakt mit uns aufnehmen, nutzen wir Messenger im Verh\u00e4ltnis zu unseren Vertragspartnern sowie<\/p><p>im Rahmen der Vertragsanbahnung als eine vertragliche Ma\u00dfnahme und im Fall anderer<\/p><p>Interessenten und Kommunikationspartner auf Grundlage unserer berechtigten Interessen an einer<\/p><p>schnellen und effizienten Kommunikation und Erf\u00fcllung der Bed\u00fcrfnisse unser<\/p><p>Kommunikationspartner an der Kommunikation via Messenger. Ferner weisen wir Sie darauf hin,<\/p><p>dass wir die uns mitgeteilten Kontaktdaten ohne Ihre Einwilligung nicht erstmalig an die Messenger<\/p><p>\u00fcbermitteln.<\/p><p>Widerruf, Widerspruch und L\u00f6schung: Sie k\u00f6nnen jederzeit eine erteilte Einwilligung widerrufen und<\/p><p>der Kommunikation mit uns via Messenger jederzeit widersprechen. Im Fall der Kommunikation via<\/p><p>Messenger l\u00f6schen wir die Nachrichten entsprechend unseren generellen L\u00f6schrichtlinien (d.h. z.B.,<\/p><p>wie oben beschrieben, nach Ende vertraglicher Beziehungen, im Kontext von Archivierungsvorgaben<\/p><p>etc.) und sonst, sobald wir davon ausgehen k\u00f6nnen, etwaige Ausk\u00fcnfte der Kommunikationspartner<\/p><p>beantwortet zu haben, wenn kein R\u00fcckbezug auf eine vorhergehende Konversation zu erwarten ist<\/p><p>und der L\u00f6schung keine gesetzlichen Aufbewahrungspflichten entgegenstehen.<\/p><p>Vorbehalt des Verweises auf andere Kommunikationswege: Zum Abschluss m\u00f6chten wir darauf<\/p><p>hinweisen, dass wir uns aus Gr\u00fcnden Ihrer Sicherheit vorbehalten, Anfragen \u00fcber Messenger nicht zu<\/p><p>beantworten. Das ist der Fall, wenn z.B. Vertragsinterna besonderer Geheimhaltung bed\u00fcrfen oder<\/p><p>eine Antwort \u00fcber Messenger den formellen Anspr\u00fcchen nicht gen\u00fcgt. In solchen F\u00e4llen verweisen<\/p><p>wir Sie auf ad\u00e4quatere Kommunikationswege.<\/p><p>Verarbeitete Datenarten: Kontaktdaten (z.B. E-Mail, Telefonnummern), Nutzungsdaten (z.B.<\/p><p>besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B.<\/p><p>Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Betroffene Personen: Kommunikationspartner.<\/p><p>Zwecke der Verarbeitung: Kontaktanfragen und Kommunikation, Direktmarketing (z.B. per E-Mail<\/p><p>oder postalisch).<\/p><p>Rechtsgrundlagen: Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs.<\/p><p>1 S. 1 lit. f. DSGVO).<\/p><p>Bereitstellung des Onlineangebotes und Webhosting<\/p><p>Um unser Onlineangebot sicher und effizient bereitstellen zu k\u00f6nnen, nehmen wir die Leistungen von<\/p><p>einem oder mehreren Webhosting-Anbietern in Anspruch, von deren Servern (bzw. von ihnen<\/p><p>verwalteten Servern) das Onlineangebot abgerufen werden kann. Zu diesen Zwecken k\u00f6nnen wir<\/p><p>Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\u00e4t, Speicherplatz und Datenbankdienste<\/p><p>sowie Sicherheitsleistungen und technische Wartungsleistungen in Anspruch nehmen.<\/p><p>Zu den im Rahmen der Bereitstellung des Hostingangebotes verarbeiteten Daten k\u00f6nnen alle die<\/p><p>Nutzer unseres Onlineangebotes betreffenden Angaben geh\u00f6ren, die im Rahmen der Nutzung und<\/p><p>der Kommunikation anfallen. Hierzu geh\u00f6ren regelm\u00e4\u00dfig die IP-Adresse, die notwendig ist, um die<\/p><p>Inhalte von Onlineangeboten an Browser ausliefern zu k\u00f6nnen, und alle innerhalb unseres<\/p><p>Onlineangebotes oder von Webseiten get\u00e4tigten Eingaben.<\/p><p>E-Mail-Versand und -Hosting: Die von uns in Anspruch genommenen Webhosting-Leistungen<\/p><p>umfassen ebenfalls den Versand, den Empfang sowie die Speicherung von E-Mails. Zu diesen<\/p><p>Zwecken werden die Adressen der Empf\u00e4nger sowie Absender als auch weitere Informationen<\/p><p>betreffend den E-Mailversand (z.B. die beteiligten Provider) sowie die Inhalte der jeweiligen E-Mails<\/p><p>verarbeitet. Die vorgenannten Daten k\u00f6nnen ferner zu Zwecken der Erkennung von SPAM<\/p><p>verarbeitet werden. Wir bitten darum, zu beachten, dass E-Mails im Internet grunds\u00e4tzlich nicht<\/p><p>verschl\u00fcsselt versendet werden. Im Regelfall werden E-Mails zwar auf dem Transportweg<\/p><p>verschl\u00fcsselt, aber (sofern kein sogenanntes Ende-zu-Ende-Verschl\u00fcsselungsverfahren eingesetzt<\/p><p>wird) nicht auf den Servern, von denen sie abgesendet und empfangen werden. Wir k\u00f6nnen daher<\/p><p>f\u00fcr den \u00dcbertragungsweg der E-Mails zwischen dem Absender und dem Empfang auf unserem Server<\/p><p>keine Verantwortung \u00fcbernehmen.<\/p><p>Erhebung von Zugriffsdaten und Logfiles: Wir selbst (bzw. unser Webhostinganbieter) erheben Daten<\/p><p>zu jedem Zugriff auf den Server (sogenannte Serverlogfiles). Zu den Serverlogfiles k\u00f6nnen die Adresse<\/p><p>und Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \u00fcbertragene<\/p><p>Datenmengen, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des<\/p><p>Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende<\/p><p>Provider geh\u00f6ren.<\/p><p>Die Serverlogfiles k\u00f6nnen zum einen zu Zwecken der Sicherheit eingesetzt werden, z.B., um eine<\/p><p>\u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\u00e4uchlichen Angriffen,<\/p><p>sogenannten DDoS-Attacken) und zum anderen, um die Auslastung der Server und ihre Stabilit\u00e4t<\/p><p>sicherzustellen.<\/p><p>Verarbeitete Datenarten: Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten<\/p><p>(z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B.<\/p><p>Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Betroffene Personen: Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/p><p>Rechtsgrundlagen: Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/p><p>Cloud-Dienste<\/p><p>Wir nutzen \u00fcber das Internet zug\u00e4ngliche und auf den Servern ihrer Anbieter ausgef\u00fchrte<\/p><p>Softwaredienste (sogenannte \u201eCloud-Dienste\u201c, auch bezeichnet als \u201eSoftware as a Service\u201c) f\u00fcr die<\/p><p>folgenden Zwecke: Dokumentenspeicherung und Verwaltung, Kalenderverwaltung, E-Mail-Versand,<\/p><p>Tabellenkalkulationen und Pr\u00e4sentationen, Austausch von Dokumenten, Inhalten und Informationen<\/p><p>mit bestimmten Empf\u00e4ngern oder Ver\u00f6ffentlichung von Webseiten, Formularen oder sonstigen<\/p><p>Inhalten und Informationen sowie Chats und Teilnahme an Audio- und Videokonferenzen.<\/p><p>In diesem Rahmen k\u00f6nnen personenbezogenen Daten verarbeitet und auf den Servern der Anbieter<\/p><p>gespeichert werden, soweit diese Bestandteil von Kommunikationsvorg\u00e4ngen mit uns sind oder von<\/p><p>uns sonst, wie im Rahmen dieser Datenschutzerkl\u00e4rung dargelegt, verarbeitet werden. Zu diesen<\/p><p>Daten k\u00f6nnen insbesondere Stammdaten und Kontaktdaten der Nutzer, Daten zu Vorg\u00e4ngen,<\/p><p>Vertr\u00e4gen, sonstigen Prozessen und deren Inhalte geh\u00f6ren. Die Anbieter der Cloud-Dienste<\/p><p>verarbeiten ferner Nutzungsdaten und Metadaten, die von ihnen zu Sicherheitszwecken und zur<\/p><p>Serviceoptimierung verwendet werden.<\/p><p>Sofern wir mit Hilfe der Cloud-Dienste f\u00fcr andere Nutzer oder \u00f6ffentlich zug\u00e4ngliche Webseiten<\/p><p>Formulare o.a. Dokumente und Inhalte bereitstellen, k\u00f6nnen die Anbieter Cookies auf den Ger\u00e4ten<\/p><p>der Nutzer f\u00fcr Zwecke der Webanalyse oder, um sich Einstellungen der Nutzer (z.B. im Fall der<\/p><p>Mediensteuerung) zu merken, speichern.<\/p><p>Hinweise zu Rechtsgrundlagen: Sofern wir um eine Einwilligung in den Einsatz der Cloud-Dienste<\/p><p>bitten, ist die Rechtsgrundlage der Verarbeitung die Einwilligung. Ferner kann deren Einsatz ein<\/p><p>Bestandteil unserer (vor)vertraglichen Leistungen sein, sofern der Einsatz der Cloud-Dienste in<\/p><p>diesem Rahmen vereinbart wurde. Ansonsten werden die Daten der Nutzer auf Grundlage unserer<\/p><p>berechtigten Interessen (d.h., Interesse an effizienten und sicheren Verwaltungs- und<\/p><p>Kollaborationsprozessen) verarbeitet<\/p><p>Verarbeitete Datenarten: Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail,<\/p><p>Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten (z.B.<\/p><p>besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B.<\/p><p>Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Betroffene Personen: Kunden, Besch\u00e4ftigte (z.B. Angestellte, Bewerber, ehemalige Mitarbeiter),<\/p><p>Interessenten, Kommunikationspartner.<\/p><p>Zwecke der Verarbeitung: B\u00fcro- und Organisationsverfahren.<\/p><p>Rechtsgrundlagen: Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Vertragserf\u00fcllung und<\/p><p>vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit.<\/p><ol><li>DSGVO).<\/li><\/ol><p>Eingesetzte Dienste und Diensteanbieter<\/p><p>Microsoft Clouddienste: Cloud-Speicher-Dienste; Dienstanbieter: Microsoft Corporation, One<\/p><p>Microsoft Way, Redmond, WA 98052-6399 USA; Website: https:\/\/microsoft.com\/de-de;<\/p><p>Datenschutzerkl\u00e4rung: https:\/\/privacy.microsoft.com\/de-de\/privacystatement, Sicherheitshinweise:<\/p><p>https:\/\/www.microsoft.com\/de-de\/trustcenter; Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau<\/p><p>bei Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000KzNaAAK&status=Active.<\/p><p>Werbliche Kommunikation via E-Mail, Post, Fax oder Telefon<\/p><p>Wir verarbeiten personenbezogene Daten zu Zwecken der werblichen Kommunikation, die \u00fcber<\/p><p>diverse Kan\u00e4le, wie z.B. E-Mail, Telefon, Post oder Fax, entsprechend den gesetzlichen Vorgaben<\/p><p>erfolgen kann.<\/p><p>Die Empf\u00e4nger haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen oder der werblichen<\/p><p>Kommunikation jederzeit zu widersprechen.<\/p><p>Nach Widerruf bzw. Widerspruch k\u00f6nnen wir die zum Nachweis der Einwilligung erforderlichen<\/p><p>Daten bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie<\/p><p>l\u00f6schen. Die Verarbeitung dieser Daten wird auf den Zweck einer m\u00f6glichen Abwehr von Anspr\u00fcchen<\/p><p>beschr\u00e4nkt. Ein individueller L\u00f6schungsantrag ist jederzeit m\u00f6glich, sofern zugleich das ehemalige<\/p><p>Bestehen einer Einwilligung best\u00e4tigt wird.<\/p><p>Verarbeitete Datenarten: Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail,<\/p><p>Telefonnummern).<\/p><p>Betroffene Personen: Kommunikationspartner.<\/p><p>Zwecke der Verarbeitung: Direktmarketing (z.B. per E-Mail oder postalisch).<\/p><p>Rechtsgrundlagen: Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs.<\/p><p>1 S. 1 lit. f. DSGVO).<\/p><p>Onlinemarketing<\/p><p>Wir verarbeiten personenbezogene Daten zu Zwecken des Onlinemarketings, worunter insbesondere<\/p><p>die Vermarktung von Werbefl\u00e4chen oder Darstellung von werbenden und sonstigen Inhalten<\/p><p>(zusammenfassend als \u201eInhalte\u201c bezeichnet) anhand potentieller Interessen der Nutzer sowie die<\/p><p>Messung ihrer Effektivit\u00e4t fallen kann.<\/p><p>Zu diesen Zwecken werden sogenannte Nutzerprofile angelegt und in einer Datei (sogenannte<\/p><p>\u201eCookie\u201c) gespeichert oder \u00e4hnliche Verfahren genutzt, mittels derer die f\u00fcr die Darstellung der<\/p><p>vorgenannten Inhalte relevante Angaben zum Nutzer gespeichert werden. Zu diesen Angaben<\/p><p>k\u00f6nnen z.B. betrachtete Inhalte, besuchte Webseiten, genutzte Onlinenetzwerke, aber auch<\/p><p>Kommunikationspartner und technische Angaben, wie der verwendete Browser, das verwendete<\/p><p>Computersystem sowie Angaben zu Nutzungszeiten geh\u00f6ren. Sofern Nutzer in die Erhebung ihrer<\/p><p>Standortdaten eingewilligt haben, k\u00f6nnen auch diese verarbeitet werden.<\/p><p>Es werden ebenfalls die IP-Adressen der Nutzer gespeichert. Jedoch nutzen wir zur Verf\u00fcgung<\/p><p>stehende IP-Masking-Verfahren (d.h., Pseudonymisierung durch K\u00fcrzung der IP-Adresse) zum Schutz<\/p><p>der Nutzer. Generell werden im Rahmen des Onlinemarketingverfahren keine Klardaten der Nutzer<\/p><p>(wie z.B. E-Mail-Adressen oder Namen) gespeichert, sondern Pseudonyme. D.h., wir als auch die<\/p><p>Anbieter der Onlinemarketingverfahren kennen nicht die tats\u00e4chlich Identit\u00e4t der Nutzer, sondern<\/p><p>nur die in deren Profilen gespeicherten Angaben.<\/p><p>Die Angaben in den Profilen werden im Regelfall in den Cookies oder mittels \u00e4hnlicher Verfahren<\/p><p>gespeichert. Diese Cookies k\u00f6nnen sp\u00e4ter generell auch auf anderen Webseiten die dasselbe<\/p><p>Onlinemarketingverfahren einsetzen, ausgelesen und zu Zwecken der Darstellung von Inhalten<\/p><p>analysiert als auch mit weiteren Daten erg\u00e4nzt und auf dem Server des<\/p><p>Onlinemarketingverfahrensanbieters gespeichert werden.<\/p><p>Ausnahmsweise k\u00f6nnen Klardaten den Profilen zugeordnet werden. Das ist der Fall, wenn die Nutzer<\/p><p>z.B. Mitglieder eines sozialen Netzwerks sind, dessen Onlinemarketingverfahren wir einsetzen und<\/p><p>das Netzwerk die Profile der Nutzer mit den vorgenannten Angaben verbindet. Wir bitten darum, zu<\/p><p>beachten, dass Nutzer mit den Anbietern zus\u00e4tzliche Abreden, z.B. durch Einwilligung im Rahmen der<\/p><p>Registrierung, treffen k\u00f6nnen.<\/p><p>Wir erhalten grunds\u00e4tzlich nur Zugang zu zusammengefassten Informationen \u00fcber den Erfolg unserer<\/p><p>Werbeanzeigen. Jedoch k\u00f6nnen wir im Rahmen sogenannter Konversionsmessungen pr\u00fcfen, welche<\/p><p>unserer Onlinemarketingverfahren zu einer sogenannten Konversion gef\u00fchrt haben, d.h. z.B., zu<\/p><p>einem Vertragsschluss mit uns. Die Konversionsmessung wird alleine zur Analyse des Erfolgs unserer<\/p><p>Marketingma\u00dfnahmen verwendet.<\/p><p>Solange nicht anders angegeben, bitten wir Sie davon auszugehen, dass verwendete Cookies f\u00fcr<\/p><p>einen Zeitraum von zwei Jahren gespeichert werden.<\/p><p>Hinweise zu Rechtsgrundlagen: Sofern wir die Nutzer um deren Einwilligung in den Einsatz der<\/p><p>Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten<\/p><p>werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an<\/p><p>effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem<\/p><p>Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser<\/p><p>Datenschutzerkl\u00e4rung hinweisen.<\/p><p>Verarbeitete Datenarten: Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten,<\/p><p>Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Betroffene Personen: Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten), Interessenten.<\/p><p>Zwecke der Verarbeitung: Tracking (z.B. interessens-\/verhaltensbezogenes Profiling, Nutzung von<\/p><p>Cookies), Remarketing, Besuchsaktionsauswertung, Interessenbasiertes und verhaltensbezogenes<\/p><p>Marketing, Profiling (Erstellen von Nutzerprofilen), Konversionsmessung (Messung der Effektivit\u00e4t<\/p><p>von Marketingma\u00dfnahmen), Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung<\/p><p>wiederkehrender Besucher).<\/p><p>Sicherheitsma\u00dfnahmen: IP-Masking (Pseudonymisierung der IP-Adresse).<\/p><p>Rechtsgrundlagen: Einwilligung (Art. 6 Abs. 1 S. 1 lit. a DSGVO), Berechtigte Interessen (Art. 6 Abs.<\/p><p>1 S. 1 lit. f. DSGVO).<\/p><p>Widerspruchsm\u00f6glichkeit (Opt-Out): Wir verweisen auf die Datenschutzhinweise der jeweiligen<\/p><p>Anbieter und die zu den Anbietern angegebenen Widerspruchsm\u00f6glichkeiten (sog. \\\u201cOpt-Out\\\u201c).<\/p><p>Sofern keine explizite Opt-Out-M\u00f6glichkeit angegeben wurde, besteht zum einen die M\u00f6glichkeit,<\/p><p>dass Sie Cookies in den Einstellungen Ihres Browsers abschalten. Hierdurch k\u00f6nnen jedoch<\/p><p>Funktionen unseres Onlineangebotes eingeschr\u00e4nkt werden. Wir empfehlen daher zus\u00e4tzlich die<\/p><p>folgenden Opt-Out-M\u00f6glichkeiten, die zusammenfassend auf jeweilige Gebiete gerichtet angeboten<\/p><p>werden: a) Europa: https:\/\/www.youronlinechoices.eu. b) Kanada:<\/p><p>https:\/\/www.youradchoices.ca\/choices. c) USA: https:\/\/www.aboutads.info\/choices. d)<\/p><p>Gebiets\u00fcbergreifend: https:\/\/optout.aboutads.info.<\/p><p>Eingesetzte Dienste und Diensteanbieter<\/p><p>Google Analytics: Onlinemarketing und Webanalyse; Dienstanbieter: Google Ireland Limited,<\/p><p>Gordon House, Barrow Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre<\/p><p>Parkway, Mountain View, CA 94043, USA; Website:<\/p><p>https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/; Datenschutzerkl\u00e4rung:<\/p><p>https:\/\/policies.google.com\/privacy; Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau bei<\/p><p>Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&status=Active;<\/p><p>Widerspruchsm\u00f6glichkeit (Opt-Out): Opt-Out-Plugin:<\/p><p>https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de, Einstellungen f\u00fcr die Darstellung von<\/p><p>Werbeeinblendungen: https:\/\/adssettings.google.com\/authenticated.<\/p><p>Pr\u00e4senzen in sozialen Netzwerken<\/p><p>Wir unterhalten Onlinepr\u00e4senzen innerhalb sozialer Netzwerke und verarbeiten in diesem Rahmen<\/p><p>Daten der Nutzer, um mit den dort aktiven Nutzern zu kommunizieren oder um Informationen \u00fcber<\/p><p>uns anzubieten.<\/p><p>Wir weisen darauf hin, dass dabei Daten der Nutzer au\u00dferhalb des Raumes der Europ\u00e4ischen Union<\/p><p>verarbeitet werden k\u00f6nnen. Hierdurch k\u00f6nnen sich f\u00fcr die Nutzer Risiken ergeben, weil so z.B. die<\/p><p>Durchsetzung der Rechte der Nutzer erschwert werden k\u00f6nnte. Im Hinblick auf US-Anbieter, die<\/p><p>unter dem Privacy-Shield zertifiziert sind oder vergleichbare Garantien eines sicheren<\/p><p>Datenschutzniveaus bieten, weisen wir darauf hin, dass sie sich damit verpflichten, die<\/p><p>Datenschutzstandards der EU einzuhalten.<\/p><p>Ferner werden die Daten der Nutzer innerhalb sozialer Netzwerke im Regelfall f\u00fcr Marktforschungs-<\/p><p>und Werbezwecke verarbeitet. So k\u00f6nnen z.B. anhand des Nutzungsverhaltens und sich daraus<\/p><p>ergebender Interessen der Nutzer Nutzungsprofile erstellt werden. Die Nutzungsprofile k\u00f6nnen<\/p><p>wiederum verwendet werden, um z.B. Werbeanzeigen innerhalb und au\u00dferhalb der Netzwerke zu<\/p><p>schalten, die mutma\u00dflich den Interessen der Nutzer entsprechen. Zu diesen Zwecken werden im<\/p><p>Regelfall Cookies auf den Rechnern der Nutzer gespeichert, in denen das Nutzungsverhalten und die<\/p><p>Interessen der Nutzer gespeichert werden. Ferner k\u00f6nnen in den Nutzungsprofilen auch Daten<\/p><p>unabh\u00e4ngig der von den Nutzern verwendeten Ger\u00e4te gespeichert werden (insbesondere, wenn die<\/p><p>Nutzer Mitglieder der jeweiligen Plattformen sind und bei diesen eingeloggt sind).<\/p><p>F\u00fcr eine detaillierte Darstellung der jeweiligen Verarbeitungsformen und der<\/p><p>Widerspruchsm\u00f6glichkeiten (Opt-Out) verweisen wir auf die Datenschutzerkl\u00e4rungen und Angaben<\/p><p>der Betreiber der jeweiligen Netzwerke.<\/p><p>Auch im Fall von Auskunftsanfragen und der Geltendmachung von Betroffenenrechten weisen wir<\/p><p>darauf hin, dass diese am effektivsten bei den Anbietern geltend gemacht werden k\u00f6nnen. Nur die<\/p><p>Anbieter haben jeweils Zugriff auf die Daten der Nutzer und k\u00f6nnen direkt entsprechende<\/p><p>Ma\u00dfnahmen ergreifen und Ausk\u00fcnfte geben. Sollten Sie dennoch Hilfe ben\u00f6tigen, dann k\u00f6nnen Sie<\/p><p>sich an uns wenden.<\/p><p>Verarbeitete Datenarten: Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail,<\/p><p>Telefonnummern), Inhaltsdaten (z.B. Texteingaben, Fotografien, Videos), Nutzungsdaten (z.B.<\/p><p>besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B.<\/p><p>Ger\u00e4te-Informationen, IP-Adressen).<\/p><p>Betroffene Personen: Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/p><p>Zwecke der Verarbeitung: Kontaktanfragen und Kommunikation, Tracking (z.B. interessens-<\/p><p>\/verhaltensbezogenes Profiling, Nutzung von Cookies), Remarketing, Reichweitenmessung (z.B.<\/p><p>Zugriffsstatistiken, Erkennung wiederkehrender Besucher).<\/p><p>Rechtsgrundlagen: Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/p><p>Eingesetzte Dienste und Diensteanbieter<\/p><p>Instagram : Soziales Netzwerk; Dienstanbieter: Instagram Inc., 1601 Willow Road, Menlo Park, CA,<\/p><p>94025, USA; Website: https:\/\/www.instagram.com; Datenschutzerkl\u00e4rung:<\/p><p>https:\/\/instagram.com\/about\/legal\/privacy.<\/p><p>Facebook: Soziales Netzwerk; Dienstanbieter: Facebook Ireland Ltd., 4 Grand Canal Square, Grand<\/p><p>Canal Harbour, Dublin 2, Irland, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA<\/p><p>94025, USA; Website: https:\/\/www.facebook.com; Datenschutzerkl\u00e4rung:<\/p><p>https:\/\/www.facebook.com\/about\/privacy; Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau bei<\/p><p>Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&status=Active;<\/p><p>Widerspruchsm\u00f6glichkeit (Opt-Out): Einstellungen f\u00fcr Werbeanzeigen:<\/p><p>https:\/\/www.facebook.com\/settings?tab=ads; Zus\u00e4tzliche Hinweise zum Datenschutz: Vereinbarung<\/p><p>\u00fcber gemeinsame Verarbeitung personenbezogener Daten auf Facebook-Seiten:<\/p><p>https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum, Datenschutzhinweise f\u00fcr<\/p><p>Facebook-Seiten: https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data.<\/p><p>YouTube: Soziales Netzwerk; Dienstanbieter: Google Ireland Limited, Gordon House, Barrow<\/p><p>Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain<\/p><p>View, CA 94043, USA; Datenschutzerkl\u00e4rung: https:\/\/policies.google.com\/privacy; Privacy Shield<\/p><p>(Gew\u00e4hrleistung Datenschutzniveau bei Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&status=Active;<\/p><p>Widerspruchsm\u00f6glichkeit (Opt-Out): https:\/\/adssettings.google.com\/authenticated.<\/p><p>Plugins und eingebettete Funktionen sowie Inhalte<\/p><p>Wir binden in unser Onlineangebot Funktions- und Inhaltselemente ein, die von den Servern ihrer<\/p><p>jeweiligen Anbieter (nachfolgend bezeichnet als \u201eDrittanbieter\u201d) bezogen werden. Dabei kann es sich<\/p><p>zum Beispiel um Grafiken, Videos oder Social-Media-Schaltfl\u00e4chen sowie Beitr\u00e4ge handeln<\/p><p>(nachfolgend einheitlich bezeichnet als \u201eInhalte\u201d).<\/p><p>Die Einbindung setzt immer voraus, dass die Drittanbieter dieser Inhalte die IP-Adresse der Nutzer<\/p><p>verarbeiten, da sie ohne die IP-Adresse die Inhalte nicht an deren Browser senden k\u00f6nnten. Die IP-<\/p><p>Adresse ist damit f\u00fcr die Darstellung dieser Inhalte oder Funktionen erforderlich. Wir bem\u00fchen uns,<\/p><p>nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung<\/p><p>der Inhalte verwenden. Drittanbieter k\u00f6nnen ferner sogenannte Pixel-Tags (unsichtbare Grafiken,<\/p><p>auch als \u201eWeb Beacons\u201c bezeichnet) f\u00fcr statistische oder Marketingzwecke verwenden. Durch die<\/p><p>\u201ePixel-Tags\u201c k\u00f6nnen Informationen, wie der Besucherverkehr auf den Seiten dieser Webseite,<\/p><p>ausgewertet werden. Die pseudonymen Informationen k\u00f6nnen ferner in Cookies auf dem Ger\u00e4t der<\/p><p>Nutzer gespeichert werden und unter anderem technische Informationen zum Browser und zum<\/p><p>Betriebssystem, zu verweisenden Webseiten, zur Besuchszeit sowie weitere Angaben zur Nutzung<\/p><p>unseres Onlineangebotes enthalten als auch mit solchen Informationen aus anderen Quellen<\/p><p>verbunden werden.<\/p><p>Hinweise zu Rechtsgrundlagen: Sofern wir die Nutzer um deren Einwilligung in den Einsatz der<\/p><p>Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten<\/p><p>werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an<\/p><p>effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem<\/p><p>Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser<\/p><p>Datenschutzerkl\u00e4rung hinweisen.<\/p><p>Verarbeitete Datenarten: Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten,<\/p><p>Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen),<\/p><p>Standortdaten (Daten, die den Standort des Endger\u00e4ts eines Endnutzers angeben), Bestandsdaten<\/p><p>(z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B.<\/p><p>Texteingaben, Fotografien, Videos).<\/p><p>Betroffene Personen: Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten),<\/p><p>Kommunikationspartner.<\/p><p>Zwecke der Verarbeitung: Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit,<\/p><p>Vertragliche Leistungen und Service, Sicherheitsma\u00dfnahmen, Verwaltung und Beantwortung von<\/p><p>Anfragen, Kontaktanfragen und Kommunikation, Direktmarketing (z.B. per E-Mail oder postalisch),<\/p><p>Tracking (z.B. interessens-\/verhaltensbezogenes Profiling, Nutzung von Cookies), Interessenbasiertes<\/p><p>und verhaltensbezogenes Marketing, Profiling (Erstellen von Nutzerprofilen).<\/p><p>Rechtsgrundlagen: Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO), Einwilligung (Art. 6 Abs.<\/p><p>1 S. 1 lit. a DSGVO), Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO).<\/p><p>Eingesetzte Dienste und Diensteanbieter<\/p><p>Google Fonts: Wir binden die Schriftarten (\u201eGoogle Fonts\u201c) des Anbieters Google ein, wobei die<\/p><p>Daten der Nutzer allein zu Zwecken der Darstellung der Schriftarten im Browser der Nutzer<\/p><p>verwendet werden. Die Einbindung erfolgt auf Grundlage unserer berechtigten Interessen an einer<\/p><p>technisch sicheren, wartungsfreien und effizienten Nutzung von Schriftarten, deren einheitlicher<\/p><p>Darstellung sowie unter Ber\u00fccksichtigung m\u00f6glicher lizenzrechtlicher Restriktionen f\u00fcr deren<\/p><p>Einbindung. Dienstanbieter: Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland,<\/p><p>Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA;<\/p><p>Website: https:\/\/fonts.google.com\/; Datenschutzerkl\u00e4rung: https:\/\/policies.google.com\/privacy;<\/p><p>Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau bei Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&status=Active.<\/p><p>Google Maps: Wir binden die Landkarten des Dienstes \u201cGoogle Maps\u201d des Anbieters Google ein. Zu<\/p><p>den verarbeiteten Daten k\u00f6nnen insbesondere IP-Adressen und Standortdaten der Nutzer geh\u00f6ren,<\/p><p>die jedoch nicht ohne deren Einwilligung (im Regelfall im Rahmen der Einstellungen ihrer<\/p><p>Mobilger\u00e4te vollzogen), erhoben werden; Dienstanbieter: Google Ireland Limited, Gordon House,<\/p><p>Barrow Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway,<\/p><p>Mountain View, CA 94043, USA; Website: https:\/\/cloud.google.com\/maps-platform;<\/p><p>Datenschutzerkl\u00e4rung: https:\/\/policies.google.com\/privacy; Privacy Shield (Gew\u00e4hrleistung<\/p><p>Datenschutzniveau bei Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000TRkEAAW&status=Active;<\/p><p>Widerspruchsm\u00f6glichkeit (Opt-Out): Opt-Out-Plugin:<\/p><p>https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de, Einstellungen f\u00fcr die Darstellung von<\/p><p>Werbeeinblendungen: https:\/\/adssettings.google.com\/authenticated.<\/p><p>YouTube-Videos: Videoinhalte; Dienstanbieter: Google Ireland Limited, Gordon House, Barrow<\/p><p>Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain<\/p><p>View, CA 94043, USA; Website: https:\/\/www.youtube.com; Datenschutzerkl\u00e4rung:<\/p><p>https:\/\/policies.google.com\/privacy; Privacy Shield (Gew\u00e4hrleistung Datenschutzniveau bei<\/p><p>Verarbeitung von Daten in den USA):<\/p><p>https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&status=Active;<\/p><p>Widerspruchsm\u00f6glichkeit (Opt-Out): Opt-Out-Plugin:<\/p><p>https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de, Einstellungen f\u00fcr die Darstellung von<\/p><p>Werbeeinblendungen: https:\/\/adssettings.google.com\/authenticated.<\/p><p>Vimeo-Videos: Videoinhalte; Dienstanbieter: Vimeo Inc., Attention: Legal Department, 555 West<\/p><p>18th Street New York, New York 10011, USA; Website: https:\/\/vimeo.com; Datenschutzerkl\u00e4rung:<\/p><p>https:\/\/vimeo.com\/privacy; Widerspruchsm\u00f6glichkeit (Opt-Out): Wir weisen darauf hin, dass Vimeo<\/p><p>Google Analytics einsetzen kann und verweisen hierzu auf die Datenschutzerkl\u00e4rung<\/p><p>(https:\/\/policies.google.com\/privacy) sowie die Opt-Out-M\u00f6glichkeiten f\u00fcr Google-Analytics<\/p><p>(https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de) oder die Einstellungen von Google f\u00fcr die<\/p><p>Datennutzung zu Marketingzwecken (https:\/\/adssettings.google.com\/).<\/p><p>L\u00f6schung von Daten<\/p><p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der gesetzlichen Vorgaben gel\u00f6scht, sobald<\/p><p>deren zur Verarbeitung erlaubten Einwilligungen widerrufen werden oder sonstige Erlaubnisse<\/p><p>entfallen (z.B., wenn der Zweck der Verarbeitung dieser Daten entfallen ist oder sie f\u00fcr den Zweck<\/p><p>nicht erforderlich sind).<\/p><p>Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke<\/p><p>erforderlich sind, wird deren Verarbeitung auf diese Zwecke beschr\u00e4nkt. D.h., die Daten werden<\/p><p>gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder<\/p><p>steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen oder deren Speicherung zur<\/p><p>Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte<\/p><p>einer anderen nat\u00fcrlichen oder juristischen Person erforderlich ist.<\/p><p>Weitere Hinweise zu der L\u00f6schung von personenbezogenen Daten k\u00f6nnen ferner im Rahmen der<\/p><p>einzelnen Datenschutzhinweise dieser Datenschutzerkl\u00e4rung erfolgen.<\/p><p>\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/p><p>Wir bitten Sie, sich regelm\u00e4\u00dfig \u00fcber den Inhalt unserer Datenschutzerkl\u00e4rung zu informieren. Wir<\/p><p>passen die Datenschutzerkl\u00e4rung an, sobald die \u00c4nderungen der von uns durchgef\u00fchrten<\/p><p>Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \u00c4nderungen<\/p><p>eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle<\/p><p>Benachrichtigung erforderlich wird.<\/p><p>Sofern wir in dieser Datenschutzerkl\u00e4rung Adressen und Kontaktinformationen von Unternehmen<\/p><p>und Organisationen angeben, bitten wir zu beachten, dass die Adressen sich \u00fcber die Zeit \u00e4ndern<\/p><p>k\u00f6nnen und bitten die Angaben vor Kontaktaufnahme zu pr\u00fcfen.<\/p><p>Begriffsdefinitionen<\/p><p>In diesem Abschnitt erhalten Sie eine \u00dcbersicht \u00fcber die in dieser Datenschutzerkl\u00e4rung<\/p><p>verwendeten Begrifflichkeiten. Viele der Begriffe sind dem Gesetz entnommen und vor allem im Art.<\/p><p>4 DSGVO definiert. Die gesetzlichen Definitionen sind verbindlich. Die nachfolgenden Erl\u00e4uterungen<\/p><p>sollen dagegen vor allem dem Verst\u00e4ndnis dienen. Die Begriffe sind alphabetisch sortiert.<\/p><p>Besuchsaktionsauswertung: \u201eBesuchsaktionsauswertung\u201c (englisch \u201eConversion Tracking\u201c)<\/p><p>bezeichnet ein Verfahren, mit dem die Wirksamkeit von Marketingma\u00dfnahmen festgestellt werden<\/p><p>kann. Dazu wird im Regelfall ein Cookie auf den Ger\u00e4ten der Nutzer innerhalb der Webseiten, auf<\/p><p>denen die Marketingma\u00dfnahmen erfolgen, gespeichert und dann erneut auf der Zielwebseite<\/p><p>abgerufen. Beispielsweise k\u00f6nnen wir so nachvollziehen, ob die von uns auf anderen Webseiten<\/p><p>geschalteten Anzeigen erfolgreich waren).<\/p><p>IP-Masking: Als \u201eIP-Masking\u201d wird eine Methode bezeichnet, bei der das letzte Oktett, d.h., die<\/p><p>letzten beiden Zahlen einer IP-Adresse, gel\u00f6scht wird, damit die IP-Adresse nicht mehr der<\/p><p>eindeutigen Identifizierung einer Person dienen kann. Daher ist das IP-Masking ein Mittel zur<\/p><p>Pseudonymisierung von Verarbeitungsverfahren, insbesondere im Onlinemarketing<\/p><p>Interessenbasiertes und verhaltensbezogenes Marketing: Von interessens- und\/oder<\/p><p>verhaltensbezogenem Marketing spricht man, wenn potentielle Interessen von Nutzern an Anzeigen<\/p><p>und sonstigen Inhalten m\u00f6glichst genau vorbestimmt werden. Dies geschieht anhand von Angaben<\/p><p>zu deren Vorverhalten (z.B. Aufsuchen von bestimmten Webseiten und Verweilen auf diesen,<\/p><p>Kaufverhaltens oder Interaktion mit anderen Nutzern), die in einem sogenannten Profil gespeichert<\/p><p>werden. Zu diesen Zwecken werden im Regelfall Cookies eingesetzt.<\/p><p>Konversionsmessung: Die Konversionsmessung ist ein Verfahren, mit dem die Wirksamkeit von<\/p><p>Marketingma\u00dfnahmen festgestellt werden kann. Dazu wird im Regelfall ein Cookie auf den Ger\u00e4ten<\/p><p>der Nutzer innerhalb der Webseiten, auf denen die Marketingma\u00dfnahmen erfolgen, gespeichert und<\/p><p>dann erneut auf der Zielwebseite abgerufen. Beispielsweise k\u00f6nnen wir so nachvollziehen, ob die von<\/p><p>uns auf anderen Webseiten geschalteten Anzeigen erfolgreich waren.<\/p><p>Personenbezogene Daten: \u201ePersonenbezogene Daten\u201c sind alle Informationen, die sich auf eine<\/p><p>identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen;<\/p><p>als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere<\/p><p>mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu<\/p><p>einer Online-Kennung (z.B. Cookie) oder zu einem oder mehreren besonderen Merkmalen<\/p><p>identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen,<\/p><p>wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind.<\/p><p>Profiling: Als \u201eProfiling\u201c wird jede Art der automatisierten Verarbeitung personenbezogener Daten<\/p><p>bezeichnet, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um<\/p><p>bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen (je nach Art des<\/p><p>Profilings geh\u00f6ren dazu Informationen betreffend das Alter, das Geschlecht, Standortdaten und<\/p><p>Bewegungsdaten, Interaktion mit Webseiten und deren Inhalten, Einkaufsverhalten, soziale<\/p><p>Interaktionen mit anderen Menschen) zu analysieren, zu bewerten oder, um sie vorherzusagen (z.B.<\/p><p>die Interessen an bestimmten Inhalten oder Produkten, das Klickverhalten auf einer Webseite oder<\/p><p>den Aufenthaltsort). Zu Zwecken des Profilings werden h\u00e4ufig Cookies und Web-Beacons eingesetzt.<\/p><p>Reichweitenmessung: Die Reichweitenmessung (auch als Web Analytics bezeichnet) dient der<\/p><p>Auswertung der Besucherstr\u00f6me eines Onlineangebotes und kann das Verhalten oder Interessen der<\/p><p>Besucher an bestimmten Informationen, wie z.B. Inhalten von Webseiten, umfassen. Mit Hilfe der<\/p><p>Reichweitenanalyse k\u00f6nnen Webseiteninhaber z.B. erkennen, zu welcher Zeit Besucher ihre<\/p><p>Webseite besuchen und f\u00fcr welche Inhalte sie sich interessieren. Dadurch k\u00f6nnen sie z.B. die Inhalte<\/p><p>der Webseite besser an die Bed\u00fcrfnisse ihrer Besucher anpassen. Zu Zwecken der<\/p><p>Reichweitenanalyse werden h\u00e4ufig pseudonyme Cookies und Web-Beacons eingesetzt, um<\/p><p>wiederkehrende Besucher zu erkennen und so genauere Analysen zur Nutzung eines<\/p><p>Onlineangebotes zu erhalten.<\/p><p>Remarketing: Vom \u201eRemarketing\u201c bzw. \u201eRetargeting\u201c spricht man, wenn z.B. zu Werbezwecken<\/p><p>vermerkt wird, f\u00fcr welche Produkte sich ein Nutzer auf einer Webseite interessiert hat, um den<\/p><p>Nutzer auf anderen Webseiten an diese Produkte, z.B. in Werbeanzeigen, zu erinnern.<\/p><p>Tracking: Vom \u201eTracking\u201c spricht man, wenn das Verhalten von Nutzern \u00fcber mehrere<\/p><p>Onlineangebote hinweg nachvollzogen werden kann. Im Regelfall werden im Hinblick auf die<\/p><p>genutzten Onlineangebote Verhaltens- und Interessensinformationen in Cookies oder auf Servern<\/p><p>der Anbieter der Trackingtechnologien gespeichert (sogenanntes Profiling). Diese Informationen<\/p><p>k\u00f6nnen anschlie\u00dfend z.B. eingesetzt werden, um den Nutzern Werbeanzeigen anzuzeigen, die<\/p><p>voraussichtlich deren Interessen entsprechen.<\/p><p>Verantwortlicher: Als \u201eVerantwortlicher\u201c wird die nat\u00fcrliche oder juristische Person, Beh\u00f6rde,<\/p><p>Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel<\/p><p>der Verarbeitung von personenbezogenen Daten entscheidet, bezeichnet.<\/p><p>Verarbeitung: \u201eVerarbeitung\u201c ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte<\/p><p>Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten. Der<br \/>Begriff reicht weit und umfasst praktisch jeden Umgang mit Daten, sei es das Erheben, das<\/p><p>Auswerten, das Speichern, das \u00dcbermitteln oder das L\u00f6schen.<\/p><p>Erstellt mit kostenlosem Datenschutz-Generator.de von Dr. Thomas Schwenke<\/p><\/div><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als \u201eDaten\u201c bezeichnet)<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16444","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/pages\/16444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/comments?post=16444"}],"version-history":[{"count":0,"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/pages\/16444\/revisions"}],"wp:attachment":[{"href":"http:\/\/america-latina.de\/pt\/wp-json\/wp\/v2\/media?parent=16444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}